{"id":1819,"date":"2024-07-14T19:29:47","date_gmt":"2024-07-14T17:29:47","guid":{"rendered":"https:\/\/polyrene.fr\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/"},"modified":"2024-07-14T19:29:47","modified_gmt":"2024-07-14T17:29:47","slug":"intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca","status":"publish","type":"appels_communication","link":"https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/","title":{"rendered":"Intellectual disability, TeleHealth, Autism and Congenital Anomalies (ITHACA)"},"content":{"rendered":"<h2><sup>1st<\/sup> European Workshop on interdisciplinary perspectives for Neurodevelopmental Disorders<\/h2>\n<ul>\n<li>Congress date and location: Amsterdam, Netherlands, April 20-21, 2023<\/li>\n<li>Deadline for abstracts: November 18, 2022<\/li>\n<li>Filing link: https: <a href=\"https:\/\/ern-ithaca.eu\/events\/eurondd\/submit-your-abstract\/\">\/\/ern-ithaca.eu\/events\/eurondd\/submit-your-abstract\/<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"parent":0,"template":"","tax_communication":[65],"class_list":["post-1819","appels_communication","type-appels_communication","status-publish","hentry","tax_communication-congres-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intellectual disability, TeleHealth, Autism and Congenital Anomalies (ITHACA) - Polyrene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intellectual disability, TeleHealth, Autism and Congenital Anomalies (ITHACA) - Polyrene\" \/>\n<meta property=\"og:description\" content=\"1st European Workshop on interdisciplinary perspectives for Neurodevelopmental Disorders Congress date and location: Amsterdam, Netherlands, April 20-21, 2023 Deadline for [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/\" \/>\n<meta property=\"og:site_name\" content=\"Polyrene\" \/>\n<meta property=\"og:image\" content=\"https:\/\/polyrene.fr\/wp-content\/uploads\/2023\/11\/logo-polyrene.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"833\" \/>\n\t<meta property=\"og:image:height\" content=\"369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/appels_communication\\\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\\\/\",\"url\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/appels_communication\\\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\\\/\",\"name\":\"Intellectual disability, TeleHealth, Autism and Congenital Anomalies (ITHACA) - Polyrene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/#website\"},\"datePublished\":\"2024-07-14T17:29:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/appels_communication\\\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/polyrene.fr\\\/en\\\/appels_communication\\\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/appels_communication\\\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appels \u00e0 communication\",\"item\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/appels_communication\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Congr\u00e8s\",\"item\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/tax_communication\\\/congres-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Intellectual disability, TeleHealth, Autism and Congenital Anomalies (ITHACA)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/\",\"name\":\"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/#organization\",\"name\":\"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap\",\"url\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/polyrene.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-polyrene.jpg\",\"contentUrl\":\"https:\\\/\\\/polyrene.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-polyrene.jpg\",\"width\":833,\"height\":369,\"caption\":\"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap\"},\"image\":{\"@id\":\"https:\\\/\\\/polyrene.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intellectual disability, TeleHealth, Autism and Congenital Anomalies (ITHACA) - Polyrene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/","og_locale":"en_US","og_type":"article","og_title":"Intellectual disability, TeleHealth, Autism and Congenital Anomalies (ITHACA) - Polyrene","og_description":"1st European Workshop on interdisciplinary perspectives for Neurodevelopmental Disorders Congress date and location: Amsterdam, Netherlands, April 20-21, 2023 Deadline for [&hellip;]","og_url":"https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/","og_site_name":"Polyrene","og_image":[{"width":833,"height":369,"url":"https:\/\/polyrene.fr\/wp-content\/uploads\/2023\/11\/logo-polyrene.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/","url":"https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/","name":"Intellectual disability, TeleHealth, Autism and Congenital Anomalies (ITHACA) - Polyrene","isPartOf":{"@id":"https:\/\/polyrene.fr\/en\/#website"},"datePublished":"2024-07-14T17:29:47+00:00","breadcrumb":{"@id":"https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/polyrene.fr\/en\/appels_communication\/intellectual-disability-telehealth-autism-and-congenital-anomalies-ithaca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/polyrene.fr\/en\/accueil\/"},{"@type":"ListItem","position":2,"name":"Appels \u00e0 communication","item":"https:\/\/polyrene.fr\/en\/appels_communication\/"},{"@type":"ListItem","position":3,"name":"Congr\u00e8s","item":"https:\/\/polyrene.fr\/en\/tax_communication\/congres-en\/"},{"@type":"ListItem","position":4,"name":"Intellectual disability, TeleHealth, Autism and Congenital Anomalies (ITHACA)"}]},{"@type":"WebSite","@id":"https:\/\/polyrene.fr\/en\/#website","url":"https:\/\/polyrene.fr\/en\/","name":"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap","description":"","publisher":{"@id":"https:\/\/polyrene.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/polyrene.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/polyrene.fr\/en\/#organization","name":"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap","url":"https:\/\/polyrene.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/polyrene.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/polyrene.fr\/wp-content\/uploads\/2023\/11\/logo-polyrene.jpg","contentUrl":"https:\/\/polyrene.fr\/wp-content\/uploads\/2023\/11\/logo-polyrene.jpg","width":833,"height":369,"caption":"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap"},"image":{"@id":"https:\/\/polyrene.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/polyrene.fr\/en\/wp-json\/wp\/v2\/appels_communication\/1819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polyrene.fr\/en\/wp-json\/wp\/v2\/appels_communication"}],"about":[{"href":"https:\/\/polyrene.fr\/en\/wp-json\/wp\/v2\/types\/appels_communication"}],"wp:attachment":[{"href":"https:\/\/polyrene.fr\/en\/wp-json\/wp\/v2\/media?parent=1819"}],"wp:term":[{"taxonomy":"tax_communication","embeddable":true,"href":"https:\/\/polyrene.fr\/en\/wp-json\/wp\/v2\/tax_communication?post=1819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}