{"id":2642,"date":"2026-01-20T12:33:23","date_gmt":"2026-01-20T11:33:23","guid":{"rendered":"https:\/\/polyrene.fr\/?post_type=video&#038;p=2642"},"modified":"2026-01-20T13:48:22","modified_gmt":"2026-01-20T12:48:22","slug":"souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025","status":"publish","type":"video","link":"https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/","title":{"rendered":"Souad LOUKKAL &#8211; Esp\u00e9rance de vie des personnes en situation de polyhandicap et facteurs associ\u00e9s \u00e0 la mortalit\u00e9 &#8211; Webinaire PolyRENE 2025"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false},"video_type":[80],"class_list":["post-2642","video","type-video","status-publish","hentry","video_type-webinaire-mooc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Souad LOUKKAL - Esp\u00e9rance de vie des personnes en situation de polyhandicap et facteurs associ\u00e9s \u00e0 la mortalit\u00e9 - Webinaire PolyRENE 2025 - Polyrene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Souad LOUKKAL - Esp\u00e9rance de vie des personnes en situation de polyhandicap et facteurs associ\u00e9s \u00e0 la mortalit\u00e9 - Webinaire PolyRENE 2025 - Polyrene\" \/>\n<meta property=\"og:url\" content=\"https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Polyrene\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T12:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/polyrene.fr\/wp-content\/uploads\/2023\/11\/logo-polyrene.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"833\" \/>\n\t<meta property=\"og:image:height\" content=\"369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/video\\\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\\\/\",\"url\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/video\\\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\\\/\",\"name\":\"Souad LOUKKAL - Esp\u00e9rance de vie des personnes en situation de polyhandicap et facteurs associ\u00e9s \u00e0 la mortalit\u00e9 - Webinaire PolyRENE 2025 - Polyrene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/#website\"},\"datePublished\":\"2026-01-20T11:33:23+00:00\",\"dateModified\":\"2026-01-20T12:48:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/video\\\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/polyrene.fr\\\/es\\\/video\\\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/video\\\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webinaire \\\/ MOOC\",\"item\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/video_type\\\/webinaire-mooc\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Souad LOUKKAL &#8211; Esp\u00e9rance de vie des personnes en situation de polyhandicap et facteurs associ\u00e9s \u00e0 la mortalit\u00e9 &#8211; Webinaire PolyRENE 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/\",\"name\":\"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/#organization\",\"name\":\"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap\",\"url\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/polyrene.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-polyrene.jpg\",\"contentUrl\":\"https:\\\/\\\/polyrene.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-polyrene.jpg\",\"width\":833,\"height\":369,\"caption\":\"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap\"},\"image\":{\"@id\":\"https:\\\/\\\/polyrene.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Souad LOUKKAL - Esp\u00e9rance de vie des personnes en situation de polyhandicap et facteurs associ\u00e9s \u00e0 la mortalit\u00e9 - Webinaire PolyRENE 2025 - Polyrene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Souad LOUKKAL - Esp\u00e9rance de vie des personnes en situation de polyhandicap et facteurs associ\u00e9s \u00e0 la mortalit\u00e9 - Webinaire PolyRENE 2025 - Polyrene","og_url":"https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/","og_site_name":"Polyrene","article_modified_time":"2026-01-20T12:48:22+00:00","og_image":[{"width":833,"height":369,"url":"https:\/\/polyrene.fr\/wp-content\/uploads\/2023\/11\/logo-polyrene.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/","url":"https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/","name":"Souad LOUKKAL - Esp\u00e9rance de vie des personnes en situation de polyhandicap et facteurs associ\u00e9s \u00e0 la mortalit\u00e9 - Webinaire PolyRENE 2025 - Polyrene","isPartOf":{"@id":"https:\/\/polyrene.fr\/es\/#website"},"datePublished":"2026-01-20T11:33:23+00:00","dateModified":"2026-01-20T12:48:22+00:00","breadcrumb":{"@id":"https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/polyrene.fr\/es\/video\/souad-loukkal-esperance-de-vie-des-personnes-en-situation-de-polyhandicap-et-facteurs-associes-a-la-mortalite-webinaire-polyrene-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/polyrene.fr\/es\/"},{"@type":"ListItem","position":2,"name":"Webinaire \/ MOOC","item":"https:\/\/polyrene.fr\/es\/video_type\/webinaire-mooc\/"},{"@type":"ListItem","position":3,"name":"Souad LOUKKAL &#8211; Esp\u00e9rance de vie des personnes en situation de polyhandicap et facteurs associ\u00e9s \u00e0 la mortalit\u00e9 &#8211; Webinaire PolyRENE 2025"}]},{"@type":"WebSite","@id":"https:\/\/polyrene.fr\/es\/#website","url":"https:\/\/polyrene.fr\/es\/","name":"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap","description":"","publisher":{"@id":"https:\/\/polyrene.fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/polyrene.fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/polyrene.fr\/es\/#organization","name":"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap","url":"https:\/\/polyrene.fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/polyrene.fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/polyrene.fr\/wp-content\/uploads\/2023\/11\/logo-polyrene.jpg","contentUrl":"https:\/\/polyrene.fr\/wp-content\/uploads\/2023\/11\/logo-polyrene.jpg","width":833,"height":369,"caption":"Polyrene - Le r\u00e9seau communautaire fran\u00e7ais de recherche autour du polyhandicap"},"image":{"@id":"https:\/\/polyrene.fr\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/polyrene.fr\/es\/wp-json\/wp\/v2\/video\/2642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polyrene.fr\/es\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/polyrene.fr\/es\/wp-json\/wp\/v2\/types\/video"}],"wp:attachment":[{"href":"https:\/\/polyrene.fr\/es\/wp-json\/wp\/v2\/media?parent=2642"}],"wp:term":[{"taxonomy":"video_type","embeddable":true,"href":"https:\/\/polyrene.fr\/es\/wp-json\/wp\/v2\/video_type?post=2642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}